{"id":670,"date":"2016-12-22T14:02:35","date_gmt":"2016-12-22T13:02:35","guid":{"rendered":"http:\/\/xtream.be\/blog\/?p=670"},"modified":"2020-04-27T13:59:30","modified_gmt":"2020-04-27T11:59:30","slug":"ma-selection-de-logiciels-gratuits","status":"publish","type":"post","link":"https:\/\/xtream.be\/blog\/ma-selection-de-logiciels-gratuits\/","title":{"rendered":"Ma s\u00e9lection de logiciels gratuits (12\/2016)"},"content":{"rendered":"<h2>Images \/ Photos<\/h2>\n<table>\n<tbody>\n<tr>\n<td><a href=\"http:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_krita.jpg\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-691 size-medium\" src=\"http:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_krita-300x188.jpg\" width=\"300\" height=\"188\" srcset=\"https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_krita-300x188.jpg 300w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_krita-768x480.jpg 768w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_krita-1024x640.jpg 1024w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_krita-282x176.jpg 282w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_krita-596x373.jpg 596w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_krita-438x274.jpg 438w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_krita.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/td>\n<td style=\"vertical-align: top;\"><strong>Retouche photo (1) : Krita (Windows, Linux, Mac)<\/strong><\/p>\n<p><u>Description :<\/u> \u00e7a ressemble \u00e0 photoshop, \u00e7a a les raccourcis claviers des photoshop et pour mon usage basique, \u00e7a a remplac\u00e9 photoshop.<\/p>\n<p>Site officiel :\u00a0<a href=\"https:\/\/krita.org\/en\/download\/krita-desktop\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/krita.org\/en\/download\/krita-desktop<\/a><\/td>\n<\/tr>\n<p><!-- \/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/ --><\/p>\n<tr>\n<td><a href=\"http:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_paint.jpg\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-694 size-medium\" src=\"http:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_paint-300x178.jpg\" width=\"300\" height=\"178\" srcset=\"https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_paint-300x178.jpg 300w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_paint-768x457.jpg 768w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_paint-1024x609.jpg 1024w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_paint-282x168.jpg 282w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_paint-596x354.jpg 596w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_paint-438x260.jpg 438w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_paint.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/td>\n<td style=\"vertical-align: top;\"><strong>Retouche photo (2) : Paint.NET (uniquement Windows)<\/strong><\/p>\n<p>Site officiel : <a href=\"http:\/\/www.getpaint.net\/index.html\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/www.getpaint.net\/index.html<\/a><\/td>\n<\/tr>\n<p><!-- \/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/ --><\/p>\n<tr>\n<td><a href=\"http:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_faststone.jpg\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-695 size-medium\" src=\"http:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_faststone-300x159.jpg\" width=\"300\" height=\"159\" srcset=\"https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_faststone-300x159.jpg 300w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_faststone-768x407.jpg 768w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_faststone-1024x542.jpg 1024w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_faststone-282x149.jpg 282w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_faststone-596x316.jpg 596w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_faststone-438x232.jpg 438w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_faststone.jpg 1127w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/td>\n<td style=\"vertical-align: top;\"><strong>Visualiseur d&rsquo;images : FastStone Image Viewer<\/strong><\/p>\n<p><u>Description :<\/u> un visualiseur d&rsquo;image qui fait aussi de la conversion par lot et qui g\u00e8re tout les formats. Il fait aussi de la mini-retouche mais je l&rsquo;utilise pas pour \u00e7a.<\/p>\n<p>Site officiel :\u00a0<a href=\"http:\/\/www.faststone.org\/FSViewerDetail.htm\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/www.faststone.org\/FSViewerDetail.htm<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<h2>Vid\u00e9os<\/h2>\n<table>\n<tbody>\n<tr>\n<td><a href=\"http:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_mpc.jpg\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-709 size-medium\" src=\"http:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_mpc-300x199.jpg\" width=\"300\" height=\"199\" srcset=\"https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_mpc-300x199.jpg 300w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_mpc-768x510.jpg 768w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_mpc-1024x680.jpg 1024w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_mpc-282x187.jpg 282w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_mpc-596x396.jpg 596w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_mpc-438x291.jpg 438w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_mpc.jpg 1088w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/td>\n<td style=\"vertical-align: top;\"><strong>Regarder des vid\u00e9os : MPC-HC (Media Player Classic Home Cinema)<\/strong><\/p>\n<p><u>Description :<\/u> l\u00e9ger, simples, efficace, int\u00e8gre tout les CODECS pour lire tout les formats<\/p>\n<p>Site officiel :\u00a0<a href=\"https:\/\/mpc-hc.org\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/mpc-hc.org<\/a><\/td>\n<\/tr>\n<p><!-- \/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/ --><\/p>\n<tr>\n<td><a href=\"http:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_davinci_resolve.jpg\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-696 size-medium\" src=\"http:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_davinci_resolve-300x169.jpg\" width=\"300\" height=\"169\" srcset=\"https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_davinci_resolve-300x169.jpg 300w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_davinci_resolve-768x432.jpg 768w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_davinci_resolve-1024x576.jpg 1024w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_davinci_resolve-282x159.jpg 282w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_davinci_resolve-596x335.jpg 596w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_davinci_resolve-438x246.jpg 438w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_davinci_resolve.jpg 1921w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/td>\n<td style=\"vertical-align: top;\"><strong>Montage vid\u00e9o : DaVinci Resolve<\/strong><\/p>\n<p><u>Description :<\/u> le p&rsquo;tit nouveau d\u00e9couvert tout r\u00e9cemment, \u00e7a a remplac\u00e9 Sony Vegas chez moi.<\/p>\n<p>Site officiel :\u00a0<a href=\"https:\/\/www.blackmagicdesign.com\/fr\/products\/davinciresolve\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.blackmagicdesign.com\/fr\/products\/davinciresolve<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<h2>Musiques<\/h2>\n<table>\n<tbody>\n<tr>\n<td><a href=\"http:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_musicBee.jpg\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-688 alignleft\" src=\"http:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_musicBee-300x214.jpg\" alt=\"\" width=\"300\" height=\"214\" srcset=\"https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_musicBee-300x214.jpg 300w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_musicBee-768x549.jpg 768w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_musicBee-1024x732.jpg 1024w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_musicBee-282x202.jpg 282w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_musicBee-596x426.jpg 596w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_musicBee-438x313.jpg 438w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_musicBee.jpg 1603w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/td>\n<td style=\"vertical-align: top;\"><strong>Ecouter de la musique : MusicBee<\/strong><\/p>\n<p><u>Description :<\/u> jolie, skinnable, gestion des pochettes et tags ID3, synchro avec t\u00e9l\u00e9phone\/ipod, radios internet, le seul vrai rempla\u00e7ant de Winamp&#8230;<\/p>\n<p>Site officiel :\u00a0<a href=\"http:\/\/getmusicbee.com\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/getmusicbee.com<\/a><\/td>\n<\/tr>\n<p><!-- \/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/ --><\/p>\n<tr>\n<td><a href=\"http:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_reaper.jpg\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-698 size-medium\" src=\"http:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_reaper-300x161.jpg\" width=\"300\" height=\"161\" srcset=\"https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_reaper-300x161.jpg 300w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_reaper-768x412.jpg 768w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_reaper-1024x550.jpg 1024w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_reaper-282x151.jpg 282w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_reaper-596x320.jpg 596w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_reaper-438x235.jpg 438w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_reaper.jpg 1500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/td>\n<td style=\"vertical-align: top;\"><strong>S\u00e9quenceur audio \/ midi \/ VSTi : Reaper <\/strong><\/p>\n<p><u>Description :<\/u> je ne l&rsquo;utilise pas car j&rsquo;ai achet\u00e9 Cubase, mais il a tr\u00e8s bonne presse. Il n&rsquo;est pas vraiment gratuit, mais on peut l&rsquo;essayer avec toutes les fonctionnalit\u00e9s pendant assez longtemps, et y a juste un d\u00e9compte au lancement qui oblige \u00e0 attendre un peu.<\/p>\n<p>Site officiel :\u00a0<a href=\"http:\/\/reaper.fm\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/reaper.fm<\/a><\/p>\n<p>Si vous aimez le m\u00e9tal, je vous conseille la chaine youtube de Leo Moracchioli, qui fait de super reprise m\u00e9tal, et tout \u00e7a avec Reaper, \u00e7a fait une bonne carte de visite \u00e0 ce logiciel : <a href=\"https:\/\/www.youtube.com\/user\/leolego\/videos\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.youtube.com\/user\/leolego\/videos<\/a><\/td>\n<\/tr>\n<p><!-- \/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/ --><\/p>\n<tr>\n<td><a href=\"http:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_ocenaudio.jpg\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-689 alignleft\" src=\"http:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_ocenaudio-300x188.jpg\" alt=\"\" width=\"300\" height=\"188\" srcset=\"https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_ocenaudio-300x188.jpg 300w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_ocenaudio-768x480.jpg 768w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_ocenaudio-1024x640.jpg 1024w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_ocenaudio-282x176.jpg 282w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_ocenaudio-596x373.jpg 596w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_ocenaudio-438x274.jpg 438w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_ocenaudio.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/td>\n<td style=\"vertical-align: top;\"><strong>Edition sonore (1) : Ocenaudio<\/strong><\/p>\n<p><u>Description :<\/u> c&rsquo;est simple, c&rsquo;est beau, facile de travailler sur plusieurs fichiers \u00e0 la fois et de switcher de l&rsquo;un a l&rsquo;autre, pleins de formats g\u00e9r\u00e9s.<\/p>\n<p>Site officiel : <a href=\"https:\/\/www.ocenaudio.com\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.ocenaudio.com<\/a><\/p>\n<p>&nbsp;<\/td>\n<\/tr>\n<p><!-- \/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/ --><\/p>\n<tr>\n<td><a href=\"http:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_audacity.jpg\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-697 size-medium\" src=\"http:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_audacity-300x194.jpg\" width=\"300\" height=\"194\" srcset=\"https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_audacity-300x194.jpg 300w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_audacity-768x498.jpg 768w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_audacity-282x183.jpg 282w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_audacity-596x386.jpg 596w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_audacity-438x284.jpg 438w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_audacity.jpg 940w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <\/a><\/td>\n<td style=\"vertical-align: top;\"><strong>Edition sonore (2) : Audacity<\/strong><\/p>\n<p><u>Description :<\/u> il est gratuit, opensource, multiplateforme et peut \u00eatre m\u00eame plus puissant qu&rsquo;Ocenaudio, mais il est moche, et moi j&rsquo;ai du mal avec les softs moche. C&rsquo;est pour \u00e7a que je suis pass\u00e9 sur Ocenaudio, mais \u00e7a reste une r\u00e9f\u00e9rence.<\/p>\n<p>Site officiel :\u00a0<a href=\"http:\/\/audacity.fr\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/audacity.fr<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<h3>Utilitaires<\/h3>\n<table>\n<tbody>\n<tr>\n<td><a href=\"http:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_sumatra.jpg\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-693 size-medium\" src=\"http:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_sumatra-300x206.jpg\" width=\"300\" height=\"206\" srcset=\"https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_sumatra-300x206.jpg 300w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_sumatra-768x528.jpg 768w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_sumatra-282x194.jpg 282w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_sumatra-596x410.jpg 596w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_sumatra-438x301.jpg 438w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_sumatra.jpg 941w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/td>\n<td style=\"vertical-align: top;\"><strong>Lecteur PDF : Sumatra PDF<\/strong><\/p>\n<p><u>Description :<\/u> adieu Acrobat Reader et son extr\u00eame lourdeur, ces mises \u00e0 jour qui p\u00e8se une tonne&#8230; Sumatra n&rsquo;est pas tr\u00e8s beau, mais on vois tr\u00e8s peu son interface&#8230;<\/p>\n<p>Site officiel :\u00a0<a href=\"https:\/\/www.sumatrapdfreader.org\/free-pdf-reader-fr.html\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.sumatrapdfreader.org\/free-pdf-reader-fr.html<\/a><\/td>\n<\/tr>\n<p><!-- \/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/ --><\/p>\n<tr>\n<td><a href=\"http:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_burnaware.jpg\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-699 size-medium\" src=\"http:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_burnaware-300x254.jpg\" width=\"300\" height=\"254\" srcset=\"https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_burnaware-300x254.jpg 300w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_burnaware-282x239.jpg 282w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_burnaware-438x372.jpg 438w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_burnaware.jpg 547w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/td>\n<td style=\"vertical-align: top;\"><strong>Gravure de CD\/DVD\/Bluray : BurnAware<\/strong><\/p>\n<p><u>Description :<\/u> c&rsquo;est gratuit, \u00e7a marche. Pourquoi payer pour Nero Burning ROM ???<\/p>\n<p>Site officiel :\u00a0<a href=\"http:\/\/www.burnaware.com\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/www.burnaware.com<\/a><\/td>\n<\/tr>\n<p><!-- \/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/ --><\/p>\n<tr>\n<td><a href=\"http:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_replicator.jpg\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-702 size-medium\" src=\"http:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_replicator-300x239.jpg\" width=\"300\" height=\"239\" srcset=\"https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_replicator-300x239.jpg 300w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_replicator-282x225.jpg 282w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_replicator-596x475.jpg 596w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_replicator-438x349.jpg 438w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_replicator.jpg 701w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/td>\n<td style=\"vertical-align: top;\"><strong>Sauvegarde p\u00e9riodique de fichiers\/dossiers : Karen Replicator<\/strong><\/p>\n<p><u>Description :<\/u> Karen (la d\u00e9veloppeuse) est d\u00e9c\u00e9d\u00e9e en 2011, mais ses utilitaires pour Windows lui rendent hommage.<br \/>\nSite officiel :\u00a0<a href=\"http:\/\/karen-s-replicator.software.informer.com\/3.6\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/karen-s-replicator.software.informer.com\/3.6<\/a><\/td>\n<\/tr>\n<p><!-- \/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/ --><\/p>\n<tr>\n<td><a href=\"http:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_ant_renamer.jpg\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-687 alignleft\" src=\"http:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_ant_renamer-300x251.jpg\" alt=\"\" width=\"300\" height=\"251\" srcset=\"https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_ant_renamer-300x251.jpg 300w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_ant_renamer-282x236.jpg 282w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_ant_renamer-596x499.jpg 596w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_ant_renamer-438x367.jpg 438w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_ant_renamer.jpg 687w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/td>\n<td style=\"vertical-align: top;\"><strong>Renommage par lots : Ant Renamer<\/strong><\/p>\n<p><u>Description :<\/u> renommer plein de fichiers d&rsquo;un coup, je n&rsquo;ai pas trouv\u00e9 mieux.<\/p>\n<p>Site officiel :\u00a0<a href=\"http:\/\/www.antp.be\/software\/renamer\/fr\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/www.antp.be\/software\/renamer\/fr<\/a><\/td>\n<\/tr>\n<p><!-- \/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/ --><\/p>\n<tr>\n<td><a href=\"http:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_clover.jpg\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-720\" src=\"http:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_clover-300x141.jpg\" alt=\"\" width=\"300\" height=\"141\" srcset=\"https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_clover-300x141.jpg 300w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_clover-768x361.jpg 768w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_clover-1024x482.jpg 1024w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_clover-282x133.jpg 282w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_clover-596x280.jpg 596w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_clover-438x206.jpg 438w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_clover.jpg 1277w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/td>\n<td style=\"vertical-align: top;\"><strong>Des\u00a0onglets dans l&rsquo;explorateur de fichiers Windows : Clover<\/strong><\/p>\n<p><u>Description :<\/u> Il apporte les onglets \u00e0 l&rsquo;explorateur de fichiers Windows, ainsi qu&rsquo;une barre de favoris et les raccourcis clavier standard de chrome (CTRL+T pour ouvrir un onglet, &#8230;). attention : logiciel uniquement en anglais, avec un installeur en chinois (glups!)<\/p>\n<p>Site officiel :\u00a0<a href=\"http:\/\/ejie.me\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/ejie.me<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<h3>R\u00e9seau<\/h3>\n<table>\n<tbody>\n<tr>\n<td><a href=\"http:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_deluge.jpg\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-701 size-medium\" src=\"http:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_deluge-300x193.jpg\" width=\"300\" height=\"193\" srcset=\"https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_deluge-300x193.jpg 300w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_deluge-768x494.jpg 768w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_deluge-1024x659.jpg 1024w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_deluge-282x181.jpg 282w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_deluge-596x384.jpg 596w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_deluge-438x282.jpg 438w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_deluge.jpg 1111w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/td>\n<td style=\"vertical-align: top;\"><strong>Client BitTorrent : Deluge<\/strong><\/p>\n<p><u>Description :<\/u> un client l\u00e9ger, s\u00e9curis\u00e9, qui g\u00e8re les listes peer block.<\/p>\n<p>Site officiel :\u00a0<a href=\"http:\/\/deluge-torrent.org\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/deluge-torrent.org<\/a><\/p>\n<p>Cet article int\u00e9ressant explique comment s\u00e9curiser ses t\u00e9l\u00e9chargements torrent (autant que possible) : <a href=\"https:\/\/www.security-helpzone.com\/securite\/deluge-chiffrer-ses-echanges-torrents.html\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.security-helpzone.com\/securite\/deluge-chiffrer-ses-echanges-torrents.html<\/a><\/td>\n<\/tr>\n<p><!-- \/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/\/ --><\/p>\n<tr>\n<td><a href=\"http:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_mobaxterm.jpg\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-703 size-medium\" src=\"http:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_mobaxterm-300x168.jpg\" width=\"300\" height=\"168\" srcset=\"https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_mobaxterm-300x168.jpg 300w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_mobaxterm-768x430.jpg 768w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_mobaxterm-1024x574.jpg 1024w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_mobaxterm-282x158.jpg 282w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_mobaxterm-596x334.jpg 596w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_mobaxterm-438x245.jpg 438w, https:\/\/xtream.be\/blog\/wp-content\/uploads\/2016\/12\/soft_mobaxterm.jpg 1467w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/td>\n<td style=\"vertical-align: top;\"><strong>Terminal \/ client SSH \/ serveur X : mobaXterm<\/strong><\/p>\n<p><u>Description :<\/u> au boulot, c&rsquo;est indispensable. Si vous avez d\u00e9j\u00e0 essay\u00e9 de monter un tunnel SSH avec putty, essayez mobaXterm, vous allez \u00eatre bluff\u00e9 \ud83d\ude42<\/p>\n<p>Site officiel :\u00a0<a href=\"http:\/\/mobaxterm.mobatek.net\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/mobaxterm.mobatek.net<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<div class=\"entry-summary\">\nMa s\u00e9lection de logiciels gratuits pour Windows, dans des domaines vari\u00e9s (image\/photo, vid\u00e9o, bureautique, r\u00e9seau, utilitaires&#8230;)\n<\/div>\n<div class=\"link-more\"><a href=\"https:\/\/xtream.be\/blog\/ma-selection-de-logiciels-gratuits\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &ldquo;Ma s\u00e9lection de logiciels gratuits (12\/2016)&rdquo;<\/span>&hellip;<\/a><\/div>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[40],"tags":[],"class_list":["post-670","post","type-post","status-publish","format-standard","hentry","category-win10","entry"],"_links":{"self":[{"href":"https:\/\/xtream.be\/blog\/wp-json\/wp\/v2\/posts\/670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xtream.be\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xtream.be\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xtream.be\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/xtream.be\/blog\/wp-json\/wp\/v2\/comments?post=670"}],"version-history":[{"count":24,"href":"https:\/\/xtream.be\/blog\/wp-json\/wp\/v2\/posts\/670\/revisions"}],"predecessor-version":[{"id":1144,"href":"https:\/\/xtream.be\/blog\/wp-json\/wp\/v2\/posts\/670\/revisions\/1144"}],"wp:attachment":[{"href":"https:\/\/xtream.be\/blog\/wp-json\/wp\/v2\/media?parent=670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xtream.be\/blog\/wp-json\/wp\/v2\/categories?post=670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xtream.be\/blog\/wp-json\/wp\/v2\/tags?post=670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}